{"id":58,"date":"2024-01-25T17:17:46","date_gmt":"2024-01-25T16:17:46","guid":{"rendered":"https:\/\/clients.mon-studio-web.com\/1a1a-new\/?page_id=58"},"modified":"2025-08-20T11:58:37","modified_gmt":"2025-08-20T09:58:37","slug":"mentions-legales","status":"publish","type":"page","link":"https:\/\/clients.mon-studio-web.com\/1a1a-new\/mentions-legales\/","title":{"rendered":"Mentions l\u00e9gales"},"content":{"rendered":"<div class=\"et_pb_section_0 et_pb_section et_section_regular et_block_section preset--module--divi-section--default\">\n<div class=\"et_pb_row_0 et_pb_row et_block_row preset--module--divi-row--default\">\n<div class=\"et_pb_column_0 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_text_0 et_pb_text et_pb_bg_layout_light et_pb_module et_flex_module\"><div class=\"et_pb_text_inner\"><h2 class=\"wp-block-heading\">1. \u00c9diteur du site<\/h2>\n<p>Le pr\u00e9sent site est \u00e9dit\u00e9 par :<\/p>\n<p><strong>[Nom de l\u2019entreprise ou de l\u2019auto-entrepreneur]<\/strong><\/p>\n<p><strong>[Forme juridique : ex. SAS \/ SARL \/ Auto-entreprise]<\/strong><\/p>\n<p><strong>[Adresse compl\u00e8te]<\/strong><\/p>\n<p><strong>[T\u00e9l\u00e9phone]<\/strong><\/p>\n<p><strong>[E-mail de contact]<\/strong><\/p>\n<p><strong>Num\u00e9ro SIRET : [XXXXX]<\/strong><\/p>\n<p><strong>N\u00b0 TVA intracommunautaire : [si applicable]<\/strong><\/p>\n<p><strong>R\u00e9alisation du site : Mon studio web - https:\/\/mon-studio-web.com\/<\/strong><\/p>\n<h2 class=\"wp-block-heading\">2. Directeur de la publication<\/h2>\n<p><strong>[Nom et pr\u00e9nom du responsable l\u00e9gal ou g\u00e9rant]<\/strong><strong><\/strong><\/p>\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n<h2 class=\"wp-block-heading\">3. H\u00e9bergeur du site<\/h2>\n<p>Le site est h\u00e9berg\u00e9 par (CHOISIR ET SUPPRIMER LES AUTRES) :<\/p>\n<p><strong>OVH SAS<\/strong><\/p>\n<p>Si\u00e8ge social : 2 rue Kellermann, 59100 Roubaix, France<\/p>\n<p>T\u00e9l. : +33 (0)9 72 10 10 07<\/p>\n<p>Site : <a href=\"https:\/\/www.ovhcloud.com\">https:\/\/www.ovhcloud.com<\/a><\/p>\n<p>SAS au capital de 10 174 560 \u20ac \u2013 RCS Lille M\u00e9tropole 424 761 419 00045 \u2013 Code APE 2620Z \u2013 N\u00b0 TVA : FR 22 424 761 419<\/p>\n<p><strong>Hostinger International Ltd.<\/strong><\/p>\n<p>Adresse : 61 Lordou Vironos Street, 6023 Larnaca, Chypre<\/p>\n<p>Site : <a href=\"https:\/\/www.hostinger.fr\">https:\/\/www.hostinger.fr<\/a><\/p>\n<p>Enregistr\u00e9e \u00e0 Chypre \u2013 Company number : HE 305365<\/p>\n<p><strong>o2switch SARL<\/strong><\/p>\n<p>Si\u00e8ge social : Chemin des Pardiaux, 63000 Clermont-Ferrand, France<\/p>\n<p>T\u00e9l. : 04 44 44 60 40<\/p>\n<p>Site : <a href=\"https:\/\/www.o2switch.fr\">https:\/\/www.o2switch.fr<\/a><\/p>\n<p>SARL au capital de 100 000 \u20ac \u2013 RCS Clermont-Ferrand 510 909 807 \u2013 Code APE 6311Z \u2013 N\u00b0 TVA : FR 35 510 909 807<\/p>\n<p><strong>Gandi SAS<\/strong><\/p>\n<p>Si\u00e8ge social : 63-65 boulevard Mass\u00e9na, 75013 Paris, France<\/p>\n<p>T\u00e9l. : +33 (0)1 70 37 76 61<\/p>\n<p>Site : <a href=\"https:\/\/www.gandi.net\">https:\/\/www.gandi.net<\/a><\/p>\n<p>SAS au capital de 800 000 \u20ac \u2013 RCS Paris 423 093 459 \u2013 N\u00b0 TVA : FR 81423093459<\/p>\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n<h2 class=\"wp-block-heading\">4. Propri\u00e9t\u00e9 intellectuelle<\/h2>\n<p>L\u2019ensemble du contenu du site (textes, images, graphismes, logo, ic\u00f4nes, etc.) est la propri\u00e9t\u00e9 exclusive de l'entreprise d\u00e9finie dans la section 1. Editeur du site, sauf mention contraire.<\/p>\n<p>Toute reproduction, distribution, modification ou adaptation, totale ou partielle, est interdite sans autorisation pr\u00e9alable.<\/p>\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n<h2 class=\"wp-block-heading\">5. Responsabilit\u00e9<\/h2>\n<p>L\u2019\u00e9diteur du site ne pourra \u00eatre tenu responsable :<\/p>\n<ul class=\"wp-block-list\">\n<li>des dommages directs ou indirects caus\u00e9s au mat\u00e9riel de l\u2019utilisateur lors de l\u2019acc\u00e8s au site,<\/li>\n<li>d\u2019\u00e9ventuelles interruptions ou indisponibilit\u00e9s du site,<\/li>\n<li>de l\u2019utilisation des informations et contenus pr\u00e9sents sur le site.<\/li>\n<\/ul>\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n<h2 class=\"wp-block-heading\">6. Donn\u00e9es personnelles<\/h2>\n<p>Les informations recueillies via le formulaire de contact sont trait\u00e9es conform\u00e9ment \u00e0 la<a href=\"https:\/\/clients.mon-studio-web.com\/1a1a-new\/politique-de-confidentialite\/\" data-type=\"page\" data-id=\"3\"> Politique de confidentialit\u00e9<\/a> disponible sur ce site.<\/p>\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n<h2 class=\"wp-block-heading\">7. Cookies<\/h2>\n<p>Le site peut utiliser des cookies afin d\u2019am\u00e9liorer la navigation et r\u00e9aliser des statistiques. L\u2019utilisateur peut \u00e0 tout moment configurer son navigateur pour refuser ou supprimer les cookies.<\/p>\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n<h2 class=\"wp-block-heading\">8. Droit applicable<\/h2>\n<p>Le pr\u00e9sent site et ses mentions l\u00e9gales sont soumis au droit fran\u00e7ais.<\/p>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-58","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/clients.mon-studio-web.com\/1a1a-new\/wp-json\/wp\/v2\/pages\/58","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clients.mon-studio-web.com\/1a1a-new\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/clients.mon-studio-web.com\/1a1a-new\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/clients.mon-studio-web.com\/1a1a-new\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/clients.mon-studio-web.com\/1a1a-new\/wp-json\/wp\/v2\/comments?post=58"}],"version-history":[{"count":9,"href":"https:\/\/clients.mon-studio-web.com\/1a1a-new\/wp-json\/wp\/v2\/pages\/58\/revisions"}],"predecessor-version":[{"id":181,"href":"https:\/\/clients.mon-studio-web.com\/1a1a-new\/wp-json\/wp\/v2\/pages\/58\/revisions\/181"}],"wp:attachment":[{"href":"https:\/\/clients.mon-studio-web.com\/1a1a-new\/wp-json\/wp\/v2\/media?parent=58"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}